{"id":201,"date":"2025-10-12T08:58:47","date_gmt":"2025-10-12T08:58:47","guid":{"rendered":"https:\/\/yourlifeatlas.com\/?page_id=201"},"modified":"2025-12-11T22:36:34","modified_gmt":"2025-12-11T22:36:34","slug":"resources","status":"publish","type":"page","link":"https:\/\/yourlifeatlas.com\/de\/resources\/","title":{"rendered":"Ressourcen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"201\" class=\"elementor elementor-201\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2696c4 e-con-full e-flex e-con e-parent\" data-id=\"b2696c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bf29bfd e-flex e-con-boxed e-con e-child\" data-id=\"bf29bfd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9634053 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9634053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Resources<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c8bb91 e-flex e-con-boxed e-con e-parent\" data-id=\"1c8bb91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a36806e elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"a36806e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Resources<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45c245f elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"45c245f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Knowledge for <strong>Growth<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-114a91e custom-tabs-style2 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"114a91e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"18131230\" aria-label=\"Abas. Abra itens com &quot;Enter&quot; ou &quot;Espa\u00e7o&quot;, feche com &quot;Escape&quot; e navegue usando as teclas de &quot;Seta&quot;.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-181312301\" data-tab-title-id=\"e-n-tab-title-181312301\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-181312301\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tArticles\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-181312302\" data-tab-title-id=\"e-n-tab-title-181312302\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-181312302\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tPodcasts\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-181312303\" data-tab-title-id=\"e-n-tab-title-181312303\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-181312303\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tBooks\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-181312304\" data-tab-title-id=\"e-n-tab-title-181312304\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-181312304\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tConsultant Network\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-181312305\" data-tab-title-id=\"e-n-tab-title-181312305\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-181312305\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tOne-hour Debriefings\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-181312306\" data-tab-title-id=\"e-n-tab-title-181312306\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-181312306\" style=\"--n-tabs-title-order: 6;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tTraining\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-181312301\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312301\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-21cdfee e-con-full e-flex e-con e-child\" data-id=\"21cdfee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2e3c7a3 e-con-full e-flex e-con e-child\" data-id=\"2e3c7a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4945488 blog-post elementor-widget elementor-widget-hfe-basic-posts\" data-id=\"4945488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hfe-basic-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"hfe-posts-grid\">\n\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/10\/personality\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"436\" height=\"424\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Rectangle-50-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Personality\" loading=\"lazy\" srcset=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Rectangle-50-1.png 436w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Rectangle-50-1-300x292.png 300w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/10\/personality\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tPersonality\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tPersonality is a seed that can only develop by slow stages throughout life. There is no personality without definiteness, wholeness,...\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/10\/personality\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tRead More\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1125\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"Personality and Consciousness\" loading=\"lazy\" srcset=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness.jpeg 2000w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness-300x169.jpeg 300w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness-1024x576.jpeg 1024w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness-768x432.jpeg 768w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/personality-and-consciousness-1536x864.jpeg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tPersonality and Consciousness\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tIn a previous letter, we noted that the body itself is not included among the modes of awareness portrayed in...\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tRead More\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"hfe-post-card\">\n\t\t\t\t\t\t\t<div class=\"hfe-post-image\">\n\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness-ii\/\" rel=\"bookmark\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"Personality and Consciousness II\" loading=\"lazy\" srcset=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II.jpeg 2000w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II-300x225.jpeg 300w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II-1024x768.jpeg 1024w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II-768x576.jpeg 768w, https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Personality-and-Consciousnes-II-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"hfe-post-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"hfe-post-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness-ii\/\" rel=\"bookmark\">\n\t\t\t\t\t\t\tPersonality and Consciousness II\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"hfe-post-excerpt\">\n\t\t\t\t\t\tIn the previous letter, we noted that there are at least two types of awareness that lie outside Jung\u2019s type...\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/yourlifeatlas.com\/de\/2025\/11\/personality-and-consciousness-ii\/\" class=\"hfe-read-more\" rel=\"bookmark\">\n\t\t\t\t\t\tRead More\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d415e96 btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d415e96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/articles\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View more Articles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-181312302\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312302\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-80eaac3 e-con-full e-flex e-con e-child\" data-id=\"80eaac3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c887513 e-con-full e-flex e-con e-child\" data-id=\"c887513\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8ac08f8 e-con-full e-flex e-con e-child\" data-id=\"8ac08f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4a4e9c elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a4a4e9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>1. Introducing the Gifts Compass Inventory\u00ae (GCI)<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1344f87 elementor-widget elementor-widget-html\" data-id=\"1344f87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe title=\"Introductory Podcast\" height=\"150\" width=\"100%\" style=\"border: none;\" scrolling=\"no\" data-name=\"pb-iframe-player\" src=\"https:\/\/www.podbean.com\/player-v2\/?i=fpbzf-18a33f7-pb&from=pb6admin&share=1&download=1&rtl=0&fonts=Arial&skin=1&font-color=auto&logo_link=podcast_page&btn-skin=7\" allowfullscreen=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3ee5ac elementor-widget elementor-widget-text-editor\" data-id=\"d3ee5ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>The GCI offers a fresh approach to Swiss psychologist Carl Jung\u2019s original eight psychological types, the well validated and broadly acclaimed gifts. The GCI focuses on the personal growth and development of unique individuals. This is our inaugural podcast and we are so excited to share our understanding of type with you. We are passionate about type, and our aim is to help you understand type, how to use type to better understand yourself, to have better relationships at home, in a social setting or in the workplace.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac60e4d e-con-full e-flex e-con e-child\" data-id=\"ac60e4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3674949 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3674949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>2. The Feeling Function\u200b<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9d8fc elementor-widget elementor-widget-html\" data-id=\"7b9d8fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe title=\"The Feeling Function\" height=\"150\" width=\"100%\" style=\"border: none;\" scrolling=\"no\" data-name=\"pb-iframe-player\" src=\"https:\/\/www.podbean.com\/player-v2\/?i=zpn9s-18a33f6-pb&from=pb6admin&share=1&download=1&rtl=0&fonts=Arial&skin=1&font-color=auto&logo_link=podcast_page&btn-skin=7\" allowfullscreen=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf23450 elementor-widget elementor-widget-text-editor\" data-id=\"cf23450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>James Johnston, Anne-Liis Laane-Saez and Nicholas Toko talk about the feeling function, one of four \u201cfunctions\u201d of conscious experience. The other three functions are thinking, intuition and sensation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9fb18b e-con-full e-flex e-con e-child\" data-id=\"e9fb18b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6daa70 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a6daa70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>3. The Thinking Function\u200b<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb16de elementor-widget elementor-widget-html\" data-id=\"bcb16de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe title=\"The Thinking Function\" height=\"150\" width=\"100%\" style=\"border: none;\" scrolling=\"no\" data-name=\"pb-iframe-player\" src=\"https:\/\/www.podbean.com\/player-v2\/?i=ug56x-18a33f5-pb&from=pb6admin&share=1&download=1&rtl=0&fonts=Arial&skin=1&font-color=auto&logo_link=podcast_page&btn-skin=7\" allowfullscreen=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8154893 elementor-widget elementor-widget-text-editor\" data-id=\"8154893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJames Johnston, Anne-Liis Laane-Saez and Nicholas Toko talk about the thinking function, one of four \u201cfunctions\u201d of conscious experience. The other three functions are feeling, intuition and sensation.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-463350f btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"463350f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/podcast\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View more Podcast<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-181312303\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312303\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-967e6ca e-con-full e-flex e-con e-child\" data-id=\"967e6ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fea7305 e-con-full e-flex e-con e-child\" data-id=\"fea7305\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c141975 book-grid elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"c141975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\t\t<link id='font-awesome-css' href='https:\/\/yourlifeatlas.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/yourlifeatlas.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post Grid *\/\n\n\n\n#uc_post_grid_elementor_c141975{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_c141975.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_c141975 .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_c141975 .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_c141975 .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_c141975 .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_c141975 .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_c141975 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_c141975 .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_c141975.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_c141975:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_c141975.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_c141975.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n    justify-content: space-between;  }\n\n    #uc_post_grid_elementor_c141975 .uc_post_button   {\n     margin-top:auto;\n   }\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_c141975.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_c141975.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_c141975.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_c141975 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_c141975 .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_c141975 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_c141975 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_c141975 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_c141975 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_c141975 .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_c141975 .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_c141975 .ue_p_title{\n  pointer-events:none;\n}\n\n\n#uc_post_grid_elementor_c141975 .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_c141975 .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_c141975 .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_c141975 .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_c141975 .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_c141975_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_c141975_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_c141975_item3 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div class=\"uc_post_grid_style_one \" id=\"uc_post_grid_elementor_c141975\"  >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n\t\t\t\n\n\n\n\n<div id=\"uc_post_grid_elementor_c141975_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/yourlifeatlas.com\/de\/book\/what-color-is-your-parachute-your-guide-to-a-lifetime-of-meaningful-work-and-career-success\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/neeww.jpg\"  src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/neeww.jpg\" alt=\"neeww\" width=\"310\" height=\"466\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n                            \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/yourlifeatlas.com\/de\/book\/what-color-is-your-parachute-your-guide-to-a-lifetime-of-meaningful-work-and-career-success\/' target=\"_self\"><div class=\"ue_p_title\">What Color Is Your Parachute?: Your Guide to a Lifetime of Meaningful Work and Career Success<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n        \t<div class=\"uc_post_text\">The groundbreaking, indispensable guide to rewarding work and a fulfilling life\u2014more than ten million...<\/div>\n     \n                   \n                         \n                                              \n      <\/div>                      \n            <div class=\"uc_post_button\">\n        \n        <a class=\"uc_more_btn \" target=\"_blank\" href='https:\/\/yourlifeatlas.com\/de\/book\/what-color-is-your-parachute-your-guide-to-a-lifetime-of-meaningful-work-and-career-success\/'>\n          <div class=\"uc_btn_inner\">\n            <div class=\"uc_btn_txt\">Read More<\/div>\n                      <\/div>\n      \t<\/a>\n        \n                \n      <\/div>                           \n \t<\/div>  <\/div>      \n        \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_c141975_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/yourlifeatlas.com\/de\/book\/frodos-wound\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/589895811.jpg\"  src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/589895811.jpg\" alt=\"58989581(1)\" width=\"719\" height=\"1080\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n                            \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/yourlifeatlas.com\/de\/book\/frodos-wound\/' target=\"_self\"><div class=\"ue_p_title\">Frodo's Wound: Why The Lord of the Rings is a Great Book<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n        \t<div class=\"uc_post_text\">Why do lovers of J.R.R. Tolkien&#8217;s The Lord of the Rings trilogy return to it again and again throughout...<\/div>\n     \n                   \n                         \n                                              \n      <\/div>                      \n            <div class=\"uc_post_button\">\n        \n        <a class=\"uc_more_btn \" target=\"_blank\" href='https:\/\/yourlifeatlas.com\/de\/book\/frodos-wound\/'>\n          <div class=\"uc_btn_inner\">\n            <div class=\"uc_btn_txt\">Read More<\/div>\n                      <\/div>\n      \t<\/a>\n        \n                \n      <\/div>                           \n \t<\/div>  <\/div>      \n        \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_c141975_item3\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/yourlifeatlas.com\/de\/book\/agile-unemployment-your-guide-to-thriving-while-out-of-work\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/51rvffswRnL._SY466_1.jpg\"  src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/51rvffswRnL._SY466_1.jpg\" alt=\"51rvffswRnL\" width=\"699\" height=\"1080\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n                            \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/yourlifeatlas.com\/de\/book\/agile-unemployment-your-guide-to-thriving-while-out-of-work\/' target=\"_self\"><div class=\"ue_p_title\">Agile Unemployment: Your Guide to Thriving While Out of Work<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n        \t<div class=\"uc_post_text\">Agile Unemployment offers a fresh, empowering perspective on navigating career transitions and the challenges...<\/div>\n     \n                   \n                         \n                                              \n      <\/div>                      \n            <div class=\"uc_post_button\">\n        \n        <a class=\"uc_more_btn \" target=\"_blank\" href='https:\/\/yourlifeatlas.com\/de\/book\/agile-unemployment-your-guide-to-thriving-while-out-of-work\/'>\n          <div class=\"uc_btn_inner\">\n            <div class=\"uc_btn_txt\">Read More<\/div>\n                      <\/div>\n      \t<\/a>\n        \n                \n      <\/div>                           \n \t<\/div>  <\/div>      \n        \n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\n\n  <div id=\"uc_post_grid_elementor_c141975_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b5de2a btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6b5de2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/books\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View more Books<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-181312304\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312304\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-ea69828 e-con-full e-flex e-con e-child\" data-id=\"ea69828\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ca318a9 e-con-full e-flex e-con e-child\" data-id=\"ca318a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9bda33 elementor-widget elementor-widget-shortcode\" data-id=\"b9bda33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n    <!-- TABS MENU -->\n    <ul class=\"country-tabs-menu\">\n        <li class=\"active\" data-country=\"all\">All<\/li>\n\n                    <li data-country=\"brazil\">\n                Brazil            <\/li>\n                    <li data-country=\"cameroon\">\n                Cameroon            <\/li>\n                    <li data-country=\"germany\">\n                Germany            <\/li>\n                    <li data-country=\"hong-kong\">\n                Hong Kong            <\/li>\n                    <li data-country=\"india\">\n                India            <\/li>\n                    <li data-country=\"malta\">\n                Malta            <\/li>\n                    <li data-country=\"netherlands\">\n                Netherlands            <\/li>\n                    <li data-country=\"norway\">\n                Norway            <\/li>\n                    <li data-country=\"peru\">\n                Peru            <\/li>\n                    <li data-country=\"poland\">\n                Poland            <\/li>\n                    <li data-country=\"portugal-lisbon\">\n                Portugal \/ Lisbon            <\/li>\n                    <li data-country=\"switzerland\">\n                Switzerland            <\/li>\n                    <li data-country=\"united-kingdom\">\n                United Kingdom            <\/li>\n                    <li data-country=\"united-states\">\n                United States            <\/li>\n            <\/ul>\n\n\n    <!-- ALL TAB -->\n    <div class=\"country-tab-content active\" data-country=\"all\">\n\n        \n            \n            <h2 class=\"country-heading\">Brazil<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Gustavo-Pessoa-300x300.jpg\" alt=\"Gustavo Pessoa\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Gustavo Pessoa<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychologist, MSc., Trained Jungian Analyst<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Brazil<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/gustavo-pessoa\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Herberto-Bergmann-300x300.jpg\" alt=\"Herberto Bergmann\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Herberto Bergmann<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Certified Gifts Compass Advisor since 2016, Psychotherapist and Psycho-Organic Coach.<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Brazil<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/herberto-bergmann\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Cameroon<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Yannick-Nkoumou-300x300.jpg\" alt=\"Yannick Nkoumou\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Yannick Nkoumou<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Senior Social and Behavior Change Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Cameroon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/yannick-nkoumou\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Germany<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Max-Black-300x279.jpg\" alt=\"Max Black\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Max Black<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Germany<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/max-black\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Hong Kong<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Fanny-Wing-Fan-Ko-300x295.jpeg\" alt=\"Fanny Wing Fan Ko\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Fanny Wing Fan Ko<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Diploma Candidate, CG Jung Institute<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Hong Kong<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/fanny-wing-fan-ko\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">India<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Sudhir-Ghodke-266x300.jpg\" alt=\"Sudhir Ghodke\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Sudhir Ghodke<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Entrepreneur, Jungian Analyst, Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> India<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/sudhir-ghodke\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Malta<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dr.-Claire-Francica-300x300.jpeg\" alt=\"Dr. Claire Francica\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dr. Claire Francica<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Warranted Psychotherapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Malta<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dr-claire-francica\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Netherlands<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Birgit-Soubiers-200x300.jpg\" alt=\"Birgit Soubiers\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Birgit Soubiers<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Symbolic Therapist, Coach, Trainer<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/birgit-soubiers\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Lucille-Aaron-Wayne-300x244.jpg\" alt=\"Lucille Aaron-Wayne\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lucille Aaron-Wayne<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Licensed Therapist + Certified IFS Therapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lucille-aaron-wayne\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Marianne-Noordijk--300x300.png\" alt=\"Marianne Noordijk\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Marianne Noordijk<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst-in-Training<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/marianne-noordijk\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Norway<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Amalia-Elsa-Maria-Carli-PhD-225x300.png\" alt=\"Amalia Elsa Maria Carli, PhD\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Amalia Elsa Maria Carli, PhD<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Norway<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/amalia-elsa-maria-carli-phd\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Peru<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Arash-Golnam-300x279.jpg\" alt=\"Arash Golnam\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Arash Golnam<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Peru<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/arash-golnam\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Poland<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Bartosz-Samitowski-300x279.jpg\" alt=\"Bartosz Samitowski\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Bartosz Samitowski<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Certified Jungian Analyst, International Association for Analytical Psychology<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/bartosz-samitowski\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Lukasz-Biedrycki-300x300.png\" alt=\"Lukasz Biedrycki\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lukasz Biedrycki<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Coach and Gifts Compass Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lukasz-biedrycki\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Marcin-Bartnicki-e1764781975290-243x300.png\" alt=\"Marcin Bartnicki\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Marcin Bartnicki<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychotherapist-in-training, Polish Association of Analytical Psychology<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/marcin-bartnicki\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Portugal \/ Lisbon<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Pedro-Mendes-300x300.png\" alt=\"Pedro Mendes\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Pedro Mendes<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Psychoanalyst<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Portugal \/ Lisbon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/pedro-mendes\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">Switzerland<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Anne-Liis-300x279.jpg\" alt=\"Anne-Liis L\u00e4\u00e4ne-S\u00e1ez\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Anne-Liis L\u00e4\u00e4ne-S\u00e1ez<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Personal and Professional Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Switzerland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/anne-liis-laane-saez\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dimitri-Spiliotis-PsychD-300x300.jpg\" alt=\"Dimitri Spiliotis, PsychD\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dimitri Spiliotis, PsychD<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Counseling Psychologist, Training Candidate C. G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Switzerland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dimitri-spiliotis-psychd\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">United Kingdom<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Jerry-Gilpin-264x300.jpg\" alt=\"Jerry Gilpin\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Jerry Gilpin<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/jerry-gilpin\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Kevin-Lim-300x279.jpg\" alt=\"Kevin Lim\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Kevin Lim<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Associate Fellow of the Higher Education Academy (AFHEA), UK<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/kevin-lim\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Lindsay-Davies-300x300.jpeg\" alt=\"Lindsay Davies\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lindsay Davies<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Professional Development Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lindsay-davies\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Nicholas-Toko-300x279.jpg\" alt=\"Nicholas Toko\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Nicholas Toko<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Training Candidate, ISAP Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/nicholas-toko\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Priscila-Santos-300x279.jpeg\" alt=\"Priscila Santos\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Priscila Santos<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Depth Coaching with training in analytical psychology, NPEJ \u2013 Portuguese Center for Jungian Studies, Lisbon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/priscila-santos\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n        \n            \n            <h2 class=\"country-heading\">United States<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/04\/Dr.-Barry-Preston--300x300.png\" alt=\"Barry Preston\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Barry Preston<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Life Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/barry-preston\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dave-Bonaiuto-300x300.jpeg\" alt=\"Dave Bonaiuto\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dave Bonaiuto<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychotherapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dave-bonaiuto\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Norman-Wolfe-300x288.jpg\" alt=\"Norman Wolfe\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Norman Wolfe<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Consultant, Reverend (interfaith Minister)<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/norman-wolfe\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n\n            <\/div>\n\n\n    <!-- SINGLE COUNTRY TABS -->\n    \n        \n        <div class=\"country-tab-content\" data-country=\"brazil\">\n\n            <h2 class=\"country-heading\">Brazil<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Gustavo-Pessoa-300x300.jpg\" alt=\"Gustavo Pessoa\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Gustavo Pessoa<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychologist, MSc., Trained Jungian Analyst<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Brazil<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/gustavo-pessoa\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Herberto-Bergmann-300x300.jpg\" alt=\"Herberto Bergmann\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Herberto Bergmann<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Certified Gifts Compass Advisor since 2016, Psychotherapist and Psycho-Organic Coach.<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Brazil<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/herberto-bergmann\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"cameroon\">\n\n            <h2 class=\"country-heading\">Cameroon<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Yannick-Nkoumou-300x300.jpg\" alt=\"Yannick Nkoumou\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Yannick Nkoumou<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Senior Social and Behavior Change Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Cameroon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/yannick-nkoumou\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"germany\">\n\n            <h2 class=\"country-heading\">Germany<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Max-Black-300x279.jpg\" alt=\"Max Black\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Max Black<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Germany<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/max-black\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"hong-kong\">\n\n            <h2 class=\"country-heading\">Hong Kong<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Fanny-Wing-Fan-Ko-300x295.jpeg\" alt=\"Fanny Wing Fan Ko\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Fanny Wing Fan Ko<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Diploma Candidate, CG Jung Institute<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Hong Kong<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/fanny-wing-fan-ko\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"india\">\n\n            <h2 class=\"country-heading\">India<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Sudhir-Ghodke-266x300.jpg\" alt=\"Sudhir Ghodke\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Sudhir Ghodke<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Entrepreneur, Jungian Analyst, Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> India<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/sudhir-ghodke\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"malta\">\n\n            <h2 class=\"country-heading\">Malta<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dr.-Claire-Francica-300x300.jpeg\" alt=\"Dr. Claire Francica\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dr. Claire Francica<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Warranted Psychotherapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Malta<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dr-claire-francica\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"netherlands\">\n\n            <h2 class=\"country-heading\">Netherlands<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Birgit-Soubiers-200x300.jpg\" alt=\"Birgit Soubiers\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Birgit Soubiers<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Symbolic Therapist, Coach, Trainer<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/birgit-soubiers\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Lucille-Aaron-Wayne-300x244.jpg\" alt=\"Lucille Aaron-Wayne\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lucille Aaron-Wayne<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Licensed Therapist + Certified IFS Therapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lucille-aaron-wayne\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Marianne-Noordijk--300x300.png\" alt=\"Marianne Noordijk\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Marianne Noordijk<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst-in-Training<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Netherlands<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/marianne-noordijk\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"norway\">\n\n            <h2 class=\"country-heading\">Norway<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Amalia-Elsa-Maria-Carli-PhD-225x300.png\" alt=\"Amalia Elsa Maria Carli, PhD\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Amalia Elsa Maria Carli, PhD<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Norway<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/amalia-elsa-maria-carli-phd\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"peru\">\n\n            <h2 class=\"country-heading\">Peru<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Arash-Golnam-300x279.jpg\" alt=\"Arash Golnam\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Arash Golnam<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Diploma Candidate, C.G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Peru<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/arash-golnam\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"poland\">\n\n            <h2 class=\"country-heading\">Poland<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Bartosz-Samitowski-300x279.jpg\" alt=\"Bartosz Samitowski\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Bartosz Samitowski<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Certified Jungian Analyst, International Association for Analytical Psychology<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/bartosz-samitowski\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Lukasz-Biedrycki-300x300.png\" alt=\"Lukasz Biedrycki\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lukasz Biedrycki<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Coach and Gifts Compass Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lukasz-biedrycki\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/Marcin-Bartnicki-e1764781975290-243x300.png\" alt=\"Marcin Bartnicki\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Marcin Bartnicki<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychotherapist-in-training, Polish Association of Analytical Psychology<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Poland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/marcin-bartnicki\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"portugal-lisbon\">\n\n            <h2 class=\"country-heading\">Portugal \/ Lisbon<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/06\/Pedro-Mendes-300x300.png\" alt=\"Pedro Mendes\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Pedro Mendes<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Psychoanalyst<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Portugal \/ Lisbon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/pedro-mendes\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"switzerland\">\n\n            <h2 class=\"country-heading\">Switzerland<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Anne-Liis-300x279.jpg\" alt=\"Anne-Liis L\u00e4\u00e4ne-S\u00e1ez\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Anne-Liis L\u00e4\u00e4ne-S\u00e1ez<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Personal and Professional Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Switzerland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/anne-liis-laane-saez\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dimitri-Spiliotis-PsychD-300x300.jpg\" alt=\"Dimitri Spiliotis, PsychD\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dimitri Spiliotis, PsychD<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Counseling Psychologist, Training Candidate C. G. Jung Institute, Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> Switzerland<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dimitri-spiliotis-psychd\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"united-kingdom\">\n\n            <h2 class=\"country-heading\">United Kingdom<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Jerry-Gilpin-264x300.jpg\" alt=\"Jerry Gilpin\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Jerry Gilpin<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/jerry-gilpin\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Kevin-Lim-300x279.jpg\" alt=\"Kevin Lim\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Kevin Lim<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Associate Fellow of the Higher Education Academy (AFHEA), UK<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/kevin-lim\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Lindsay-Davies-300x300.jpeg\" alt=\"Lindsay Davies\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Lindsay Davies<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Professional Development Consultant<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/lindsay-davies\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Nicholas-Toko-300x279.jpg\" alt=\"Nicholas Toko\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Nicholas Toko<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Jungian Analyst Training Candidate, ISAP Zurich<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/nicholas-toko\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Priscila-Santos-300x279.jpeg\" alt=\"Priscila Santos\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Priscila Santos<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Depth Coaching with training in analytical psychology, NPEJ \u2013 Portuguese Center for Jungian Studies, Lisbon<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United Kingdom<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/priscila-santos\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n        \n        <div class=\"country-tab-content\" data-country=\"united-states\">\n\n            <h2 class=\"country-heading\">United States<\/h2>\n\n            <div class=\"professionals-row\">\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2026\/04\/Dr.-Barry-Preston--300x300.png\" alt=\"Barry Preston\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Barry Preston<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Life Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/barry-preston\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Dave-Bonaiuto-300x300.jpeg\" alt=\"Dave Bonaiuto\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Dave Bonaiuto<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychotherapist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/dave-bonaiuto\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"professionals-item\">\n\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Norman-Wolfe-300x288.jpg\" alt=\"Norman Wolfe\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Norman Wolfe<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Consultant, Reverend (interfaith Minister)<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                            <p><span>Country:<\/span> United States<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/consultantnetwork\/norman-wolfe\/\">See details<\/a>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    \n\n    <!-- TAB SWITCHING SCRIPT -->\n    <script>\n        document.querySelectorAll('.country-tabs-menu li').forEach(tab => {\n            tab.addEventListener('click', function () {\n\n                document.querySelectorAll('.country-tabs-menu li')\n                    .forEach(li => li.classList.remove('active'));\n\n                this.classList.add('active');\n\n                let target = this.getAttribute('data-country');\n\n                document.querySelectorAll('.country-tab-content')\n                    .forEach(content => {\n                        content.classList.remove('active');\n                        if (content.getAttribute('data-country') === target) {\n                            content.classList.add('active');\n                        }\n                    });\n\n                if (target === \"all\") {\n                    document.querySelector('.country-tab-content[data-country=\"all\"]').classList.add('active');\n                }\n\n            });\n        });\n    <\/script>\n\n    \n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d5666 btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"40d5666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/consultant-network\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View more Consultant Network<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-181312305\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312305\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-cdd3a46 e-con-full e-flex e-con e-child\" data-id=\"cdd3a46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b39d347 e-con-full e-flex e-con e-child\" data-id=\"b39d347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e507a33 elementor-widget elementor-widget-shortcode\" data-id=\"e507a33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n    <div class=\"professionals-sec\">\n        <div class=\"professionals-row\">\n\n            \n                    <div class=\"professionals-item\">\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Gustavo-Pessoa-1-300x300.jpg\" alt=\"Gustavo Pessoa\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Gustavo Pessoa<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Psychologist, MSc., Trained Jungian Analyst<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                                                            <p><span>Languages:<\/span> Portuguese, English<\/p>\n                            \n                                                            <p><span>Country:<\/span> Brazil<\/p>\n                            \n                                                            <p><span>Session Fee:<\/span> $140<\/p>\n                                                    <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/one_hour_debriefings\/gustavo-pessoa-2\/\">See details<\/a>\n                                                            <a href=\"mailto:gustavo-pessoa.com.br\">Book a Debriefings Session<\/a>\n                                                    <\/div>\n                    <\/div>\n\n                \n                    <div class=\"professionals-item\">\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-17-at-01.45.22_705eb957-e1774352018612-300x300.jpg\" alt=\"Sabrina Ricci\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Sabrina Ricci<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Coach, Translator, Artist<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                                                            <p><span>Languages:<\/span> Portuguese, English, French<\/p>\n                            \n                                                            <p><span>Country:<\/span> Brazil<\/p>\n                            \n                                                            <p><span>Session Fee:<\/span> $140<\/p>\n                                                    <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/one_hour_debriefings\/sabrina-ricci\/\">See details<\/a>\n                                                            <a href=\"mailto:sricci.giftscompass@gmail.com\">Book a Debriefings Session<\/a>\n                                                    <\/div>\n                    <\/div>\n\n                \n                    <div class=\"professionals-item\">\n                        <div class=\"professionals-featured-image\">\n                                                            <img decoding=\"async\" src=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/10\/Anne-Liis-1-300x279.jpg\" alt=\"Anne-Liis L\u00e4\u00e4ne-S\u00e1ez\">\n                                                    <\/div>\n\n                        <div class=\"professionals-title\">\n                            <h2>Anne-Liis L\u00e4\u00e4ne-S\u00e1ez<\/h2>\n                        <\/div>\n\n                        <div class=\"professionals-except\">\n                            <p>Personal and Professional Coach<\/p>\n                        <\/div>\n\n                        <div class=\"professionals-specification\">\n                                                            <p><span>Languages:<\/span> Estonian, English, French<\/p>\n                            \n                                                            <p><span>Country:<\/span> Switzerland<\/p>\n                            \n                                                            <p><span>Session Fee:<\/span> $90<\/p>\n                                                    <\/div>\n\n                        <div class=\"professionals-button\">\n                            <a href=\"https:\/\/yourlifeatlas.com\/de\/one_hour_debriefings\/anne-liis-laane-saez\/\">See details<\/a>\n                                                            <a href=\"mailto:anne-liis.giftscompass@gmail.com\">Book a Debriefings Session<\/a>\n                                                    <\/div>\n                    <\/div>\n\n                \n        <\/div>\n    <\/div>\n\n    \n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8ac7b5 btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f8ac7b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/one-hour-debriefings\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View more Debriefings<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-181312306\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-181312306\" data-tab-index=\"6\" style=\"--n-tabs-title-order: 6;\" class=\" elementor-element elementor-element-6a51b2e e-con-full e-flex e-con e-child\" data-id=\"6a51b2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8c2607 e-con-full e-flex e-con e-child\" data-id=\"a8c2607\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53fbb78 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"53fbb78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Life Atlas <strong>Consultant Training<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70dfc5b elementor-widget__width-inherit elementor-widget-laptop__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"70dfc5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Our immersive training programs go far beyond theory. They bring you into the heart of Carl Jung\u2019s <br \/>original model of psychological types\u2014not just as a theory, but as a living framework.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f84feae btn-mini-w elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f84feae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/yourlifeatlas.com\/training\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explore Our Consultant Training<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Resources Resources Knowledge for Growth Articles Podcasts Books Consultant Network One-hour Debriefings Training Orientation and Attitude \u201cYou see, you get your orientation, you get your bearings, in the chaotic abundance of impressions through the four functions,&#8230; Read More Oppositions So the birth of personality in oneself has a therapeutic effect. It is as if a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-201","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resources - Life Atlas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yourlifeatlas.com\/de\/resources\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resources\" \/>\n<meta property=\"og:description\" content=\"Resources Resources Knowledge for Growth Articles Podcasts Books Consultant Network One-hour Debriefings Training Orientation and Attitude \u201cYou see, you get your orientation, you get your bearings, in the chaotic abundance of impressions through the four functions,&#8230; Read More Oppositions So the birth of personality in oneself has a therapeutic effect. It is as if a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yourlifeatlas.com\/de\/resources\/\" \/>\n<meta property=\"og:site_name\" content=\"Life Atlas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T22:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/psychological-type-image-27.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/\",\"name\":\"Resources - Life Atlas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/psychological-type-image-27.jpg\",\"datePublished\":\"2025-10-12T08:58:47+00:00\",\"dateModified\":\"2025-12-11T22:36:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/psychological-type-image-27.jpg\",\"contentUrl\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/psychological-type-image-27.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/resources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yourlifeatlas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#website\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/\",\"name\":\"Life Atlas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourlifeatlas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resources - Life Atlas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yourlifeatlas.com\/de\/resources\/","og_locale":"de_DE","og_type":"article","og_title":"Resources","og_description":"Resources Resources Knowledge for Growth Articles Podcasts Books Consultant Network One-hour Debriefings Training Orientation and Attitude \u201cYou see, you get your orientation, you get your bearings, in the chaotic abundance of impressions through the four functions,&#8230; Read More Oppositions So the birth of personality in oneself has a therapeutic effect. It is as if a [&hellip;]","og_url":"https:\/\/yourlifeatlas.com\/de\/resources\/","og_site_name":"Life Atlas","article_modified_time":"2025-12-11T22:36:34+00:00","og_image":[{"url":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/psychological-type-image-27.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yourlifeatlas.com\/resources\/","url":"https:\/\/yourlifeatlas.com\/resources\/","name":"Resources - Life Atlas","isPartOf":{"@id":"https:\/\/yourlifeatlas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yourlifeatlas.com\/resources\/#primaryimage"},"image":{"@id":"https:\/\/yourlifeatlas.com\/resources\/#primaryimage"},"thumbnailUrl":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/psychological-type-image-27.jpg","datePublished":"2025-10-12T08:58:47+00:00","dateModified":"2025-12-11T22:36:34+00:00","breadcrumb":{"@id":"https:\/\/yourlifeatlas.com\/resources\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yourlifeatlas.com\/resources\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yourlifeatlas.com\/resources\/#primaryimage","url":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/psychological-type-image-27.jpg","contentUrl":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/psychological-type-image-27.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/yourlifeatlas.com\/resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yourlifeatlas.com\/"},{"@type":"ListItem","position":2,"name":"Resources"}]},{"@type":"WebSite","@id":"https:\/\/yourlifeatlas.com\/#website","url":"https:\/\/yourlifeatlas.com\/","name":"Lebensatlas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourlifeatlas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/pages\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":10,"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/pages\/201\/revisions"}],"predecessor-version":[{"id":4329,"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/pages\/201\/revisions\/4329"}],"wp:attachment":[{"href":"https:\/\/yourlifeatlas.com\/de\/wp-json\/wp\/v2\/media?parent=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}