{"id":2158,"date":"2025-11-10T20:15:11","date_gmt":"2025-11-10T20:15:11","guid":{"rendered":"https:\/\/yourlifeatlas.com\/?p=2158"},"modified":"2025-11-10T20:25:19","modified_gmt":"2025-11-10T20:25:19","slug":"sera-que-as-ideias-realmente-nos-dominam","status":"publish","type":"post","link":"https:\/\/yourlifeatlas.com\/pt\/2025\/11\/do-ideas-truly-have-us\/","title":{"rendered":"Ser\u00e1 que as ideias realmente nos &quot;dominam&quot;?"},"content":{"rendered":"<h3>JG Johnston<\/h3>\n<p><em><strong>\u201cAs pessoas n\u00e3o t\u00eam ideias. As ideias t\u00eam pessoas.\u201d \u2014 CG Jung<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>O que \u00e9 uma ideia?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Embora falemos de ideias com facilidade e frequ\u00eancia, pois a experi\u00eancia de ter ideias \u00e9 comum a todos n\u00f3s, ningu\u00e9m sabe realmente o que \u00e9 uma ideia em si mesma. N\u00f3s as vivenciamos e tendemos a reivindic\u00e1-las como nossas, embora na verdade n\u00e3o saibamos de onde v\u00eam ou para onde se destinam.<\/p>\n<p>&nbsp;<\/p>\n<p>Uma vis\u00e3o materialista poderia sugerir que as sinapses eletroqu\u00edmicas org\u00e2nicas em nossos c\u00e9rebros geram ideias. Demonstrou-se que essas sinapses s\u00e3o parte integrante da experi\u00eancia, mas se elas s\u00e3o causais ou colaterais \u00e9 desconhecido. As sinapses podem ser instrumentais, da mesma forma que um r\u00e1dio \u00e9 instrumental na transmiss\u00e3o do som. Mas as sinapses, assim como o r\u00e1dio, podem desempenhar apenas o papel de transmissoras de ideias, em vez de atuarem como a fonte dessas ideias.<\/p>\n<p>&nbsp;<\/p>\n<p>Parece realmente estranho pensar que as c\u00e9lulas vivas que comp\u00f5em os neur\u00f4nios possuam a intelig\u00eancia necess\u00e1ria para gerar ideias que auxiliem as pessoas a entender hor\u00e1rios de trens, criar poesias inspiradoras, escrever romances, desenvolver novas abordagens para a psicologia ou construir um arranha-c\u00e9u de cem andares. Estranho? Bem, quando refletimos mais profundamente sobre essa ideia, ela se torna claramente absurda.<\/p>\n<p>&nbsp;<\/p>\n<p>Pensamentos, ideias, pensamento profundo e n\u00e3o direcionado, pensamento direcionado e intencional \u2014 todos esses s\u00e3o fen\u00f4menos que nos s\u00e3o mist\u00e9rios insond\u00e1veis. No entanto, temos termos para identific\u00e1-los, transformando-os de puro mist\u00e9rio em fen\u00f4menos conhecidos. Se os conhecemos por meio de r\u00f3tulos, esse conhecimento obscurece a realidade insegura e incerta do que eles realmente s\u00e3o: mist\u00e9rios.<\/p>\n<p>&nbsp;<\/p>\n<p>Se recorrermos \u00e0 observa\u00e7\u00e3o de Jung \u2014 de que essas ideias, de alguma forma, nos possuem, em vez de n\u00f3s possuirmos ideias \u2014 isso nos ajuda a compreender melhor a extens\u00e3o do mist\u00e9rio. Pensamentos e ideias t\u00eam naturezas diferentes. Alguns pensamentos e ideias s\u00e3o fundamentais para a vida no mundo \u2014 qual trem pegar para ir de Genebra a Zurique, qual curso fazer para aprender a falar alem\u00e3o, como identificar a melhor maneira de ir da Fl\u00f3rida \u00e0 Calif\u00f3rnia, como seguir as instru\u00e7\u00f5es para montar um arm\u00e1rio da Ikea?<\/p>\n<p>&nbsp;<\/p>\n<p>Mas outras ideias surgem do nada, como pensamentos que suavemente invadem nossa consci\u00eancia. Essas ideias t\u00eam o poder de direcionar nossas vidas \u2014 os pensamentos que parecem nos dominar.<\/p>\n<p>&nbsp;<\/p>\n<p>Algumas parecem surgir do que Jung denominou &quot;inconsciente pessoal&quot;. Deparamo-nos com uma experi\u00eancia que ressoa com uma experi\u00eancia anterior desagrad\u00e1vel ou traum\u00e1tica, e o pensamento de reviver essa experi\u00eancia nos domina com uma ansiedade nervosa. Elas emergem de um interior obscuro e nos arrastam para um desejo obsessivo ou compulsivo de evitar mais dessas experi\u00eancias. S\u00e3o sintomas de feridas emocionais que precisam de cura.<\/p>\n<p>&nbsp;<\/p>\n<p>Outras ideias parecem preencher todo o nosso ser corp\u00f3reo com uma inspira\u00e7\u00e3o vitalizante \u2014 o tipo de ideias inspiradoras que impulsionam um romancista a escrever um novo romance. O romancista Vladimir Nabokov descreveu essas ideias inspiradoras com maestria:<\/p>\n<p>&nbsp;<\/p>\n<p>Um brilho preliminar, semelhante a uma variedade benigna da aura antes de um ataque epil\u00e9ptico, \u00e9 algo que o artista aprende a perceber muito cedo na vida. Essa sensa\u00e7\u00e3o de bem-estar formigante se espalha por ele como o vermelho e o azul na imagem de um homem esfolado sob a obra Circula\u00e7\u00e3o. \u00c0 medida que se alastra, elimina toda a consci\u00eancia do desconforto f\u00edsico \u2014 tanto a dor de dente da juventude quanto a neuralgia da velhice. A beleza disso reside no fato de que, embora completamente intelig\u00edvel (como se estivesse ligado a uma gl\u00e2ndula conhecida ou conduzisse a um cl\u00edmax esperado), n\u00e3o tem origem nem objeto. Expande-se, brilha e diminui sem revelar seu segredo. Enquanto isso, por\u00e9m, uma janela se abre, um vento auroral sopra, cada nervo exposto vibra. Logo tudo se dissolve: as preocupa\u00e7\u00f5es familiares retornam e a sobrancelha redesenha seu arco de dor; mas o artista sabe que est\u00e1 pronto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ideias desse tipo tamb\u00e9m nos dominam, pois criam a necessidade obsessiva de vivenci\u00e1-las de alguma forma. No resumo de Nabokov, o artista agora sabe que est\u00e1 pronto para embarcar nessa jornada criativa para ilustrar plenamente a ideia com uma hist\u00f3ria escrita completa.<\/p>\n<p>&nbsp;<\/p>\n<p>Fil\u00f3sofos podem ter essas ideias compulsivas. Podem apreender uma no\u00e7\u00e3o vaga, aparentemente distante, de uma ideia que necessita de maior compreens\u00e3o e express\u00e3o. Immanuel Kant, o fil\u00f3sofo do s\u00e9culo XVIII, parecia possu\u00eddo por uma dessas ideias. Ele dedicou dez anos de sua vida a circundar mentalmente uma nova e intrigante ideia, nascida de um coment\u00e1rio de David Hume, um fil\u00f3sofo contempor\u00e2neo. Nesses dez anos de peregrina\u00e7\u00e3o di\u00e1ria para desvendar uma ideia que parecia t\u00ea-lo dominado, era poss\u00edvel acertar o rel\u00f3gio por suas caminhadas vespertinas di\u00e1rias. Ele dizia aos amigos que se ausentaria de seus eventos sociais, pois estava resolutamente dedicado a compreender uma ideia que se sentia compelido a perseguir. Ap\u00f3s dez anos de reflex\u00e3o profunda, escreveu sua obra seminal, Cr\u00edtica da Raz\u00e3o Pura, um livro que abalou os alicerces das filosofias iluministas que o precederam.<\/p>\n<p>&nbsp;<\/p>\n<p>E certamente Carl Jung era obcecado por ideias. Desde cedo, sentiu-se perturbado pela incerteza quanto \u00e0 sua carreira. Estudou intensamente filosofia e medicina, mas tinha pouco entusiasmo pela vida como m\u00e9dico. Ent\u00e3o, no \u00faltimo ano de seus estudos, pegou o livro que antes lhe parecera enfadonho \u2014 o livro de psiquiatria \u2014 e, ap\u00f3s ler a introdu\u00e7\u00e3o, soube o que devia fazer. Compreender a psicologia humana tornou-se a busca de sua vida, e suas Obras Completas, em v\u00e1rios volumes, servem hoje como base para milhares de praticantes da Psicologia Anal\u00edtica de Jung.<\/p>\n<p>&nbsp;<\/p>\n<p>Ideias e pensamentos, as ideias pr\u00e1ticas sobre como navegar pela vida em um mundo f\u00edsico, as ideias e pensamentos incorporados em mem\u00f3rias emocionais, as ideias e pensamentos inspiradores que geram nova poesia, literatura, filosofia e psicologia \u2014 essas ideias e pensamentos parecem direcionar e guiar nossos caminhos de vida.<\/p>\n<p>&nbsp;<\/p>\n<p>De onde v\u00eam? N\u00e3o sabemos. O que s\u00e3o? N\u00e3o sabemos. Sabemos que fazem parte da experi\u00eancia humana, mas o que s\u00e3o e por que t\u00eam o poder de nos &quot;dominar&quot; \u00e9 um mist\u00e9rio.<\/p>\n<p>&nbsp;<\/p>\n<p>Damos nomes a esses fen\u00f4menos \u2014 ideias e pensamentos \u2014 e, ao nome\u00e1-los, nos entregamos \u00e0 falsa premissa de que os compreendemos. Mas eles s\u00e3o simplesmente elementos de uma vida repleta de nomes e r\u00f3tulos para muito do que est\u00e1 muito al\u00e9m da nossa compreens\u00e3o. Vivemos e caminhamos em completo mist\u00e9rio; muito pouco do que dizemos &quot;saber&quot; realmente compreendemos. Ideias e pensamentos s\u00e3o elementos de uma estrutura maior de consci\u00eancia. Constituem mais um elemento do mist\u00e9rio que afirmamos conhecer e possuir. Contudo, como observou Jung, nossas ideias podem, de fato, nos dominar, e n\u00e3o a nossa presun\u00e7\u00e3o de que as possu\u00edmos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>JG Johnston<\/strong> \u00e9 autor de <strong>B\u00fassola Indispens\u00e1vel de Jung<\/strong> e <strong>O caminho<\/strong> e cofundador de <strong>Atlas da Vida<\/strong>\u2014 um site que ajuda as pessoas a viverem suas melhores vidas.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cAs pessoas n\u00e3o t\u00eam ideias. As ideias t\u00eam as pessoas.\u201d \u2014 CG Jung. O que \u00e9 uma ideia? Embora falemos de ideias com facilidade e frequ\u00eancia, para a<\/p>","protected":false},"author":2,"featured_media":2161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-depth-psychology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Do Ideas Truly \u201cHave Us\u201d? - Life Atlas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yourlifeatlas.com\/pt\/2025\/11\/sera-que-as-ideias-realmente-nos-dominam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Do Ideas Truly \u201cHave Us\u201d?\" \/>\n<meta property=\"og:description\" content=\"\u201cPeople don\u2019t have ideas. Ideas have people.\u201d\u200a \u2014\u200aC. G. Jung What is an idea? Even though we speak of ideas easily and often, for the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yourlifeatlas.com\/pt\/2025\/11\/sera-que-as-ideias-realmente-nos-dominam\/\" \/>\n<meta property=\"og:site_name\" content=\"Life Atlas\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T20:15:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T20:25:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Johnston\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Johnston\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/\"},\"author\":{\"name\":\"James Johnston\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#\\\/schema\\\/person\\\/61357562a1bc0f3f0660e7bd63837b7d\"},\"headline\":\"Do Ideas Truly \u201cHave Us\u201d?\",\"datePublished\":\"2025-11-10T20:15:11+00:00\",\"dateModified\":\"2025-11-10T20:25:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/\"},\"wordCount\":1188,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/depth-psychology-image-02.jpg\",\"articleSection\":[\"Depth Psychology\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/\",\"name\":\"Do Ideas Truly \u201cHave Us\u201d? - Life Atlas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/depth-psychology-image-02.jpg\",\"datePublished\":\"2025-11-10T20:15:11+00:00\",\"dateModified\":\"2025-11-10T20:25:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#\\\/schema\\\/person\\\/61357562a1bc0f3f0660e7bd63837b7d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/depth-psychology-image-02.jpg\",\"contentUrl\":\"https:\\\/\\\/yourlifeatlas.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/depth-psychology-image-02.jpg\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/2025\\\/11\\\/do-ideas-truly-have-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yourlifeatlas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Do Ideas Truly \u201cHave Us\u201d?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#website\",\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/\",\"name\":\"Life Atlas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourlifeatlas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yourlifeatlas.com\\\/#\\\/schema\\\/person\\\/61357562a1bc0f3f0660e7bd63837b7d\",\"name\":\"James Johnston\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g\",\"caption\":\"James Johnston\"},\"url\":\"https:\\\/\\\/yourlifeatlas.com\\\/pt\\\/author\\\/jgj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ser\u00e1 que as ideias realmente nos &quot;possuem&quot;? - Atlas da Vida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yourlifeatlas.com\/pt\/2025\/11\/sera-que-as-ideias-realmente-nos-dominam\/","og_locale":"pt_BR","og_type":"article","og_title":"Do Ideas Truly \u201cHave Us\u201d?","og_description":"\u201cPeople don\u2019t have ideas. Ideas have people.\u201d\u200a \u2014\u200aC. G. Jung What is an idea? Even though we speak of ideas easily and often, for the","og_url":"https:\/\/yourlifeatlas.com\/pt\/2025\/11\/sera-que-as-ideias-realmente-nos-dominam\/","og_site_name":"Life Atlas","article_published_time":"2025-11-10T20:15:11+00:00","article_modified_time":"2025-11-10T20:25:19+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg","type":"image\/jpeg"}],"author":"James Johnston","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"James Johnston","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#article","isPartOf":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/"},"author":{"name":"James Johnston","@id":"https:\/\/yourlifeatlas.com\/#\/schema\/person\/61357562a1bc0f3f0660e7bd63837b7d"},"headline":"Do Ideas Truly \u201cHave Us\u201d?","datePublished":"2025-11-10T20:15:11+00:00","dateModified":"2025-11-10T20:25:19+00:00","mainEntityOfPage":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/"},"wordCount":1188,"commentCount":0,"image":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#primaryimage"},"thumbnailUrl":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg","articleSection":["Depth Psychology"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/","url":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/","name":"Ser\u00e1 que as ideias realmente nos &quot;possuem&quot;? - Atlas da Vida","isPartOf":{"@id":"https:\/\/yourlifeatlas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#primaryimage"},"image":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#primaryimage"},"thumbnailUrl":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg","datePublished":"2025-11-10T20:15:11+00:00","dateModified":"2025-11-10T20:25:19+00:00","author":{"@id":"https:\/\/yourlifeatlas.com\/#\/schema\/person\/61357562a1bc0f3f0660e7bd63837b7d"},"breadcrumb":{"@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#primaryimage","url":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg","contentUrl":"https:\/\/yourlifeatlas.com\/wp-content\/uploads\/2025\/11\/depth-psychology-image-02.jpg","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/yourlifeatlas.com\/2025\/11\/do-ideas-truly-have-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yourlifeatlas.com\/"},{"@type":"ListItem","position":2,"name":"Do Ideas Truly \u201cHave Us\u201d?"}]},{"@type":"WebSite","@id":"https:\/\/yourlifeatlas.com\/#website","url":"https:\/\/yourlifeatlas.com\/","name":"Atlas da Vida","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourlifeatlas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/yourlifeatlas.com\/#\/schema\/person\/61357562a1bc0f3f0660e7bd63837b7d","name":"James Johnston","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/102df6dd747f22072ed02fe7955e897b4eab3f8b67dc2d17e79c7cc988fea1c2?s=96&d=mm&r=g","caption":"James Johnston"},"url":"https:\/\/yourlifeatlas.com\/pt\/author\/jgj\/"}]}},"_links":{"self":[{"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/posts\/2158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/comments?post=2158"}],"version-history":[{"count":4,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/posts\/2158\/revisions"}],"predecessor-version":[{"id":2170,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/posts\/2158\/revisions\/2170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/media\/2161"}],"wp:attachment":[{"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/media?parent=2158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/categories?post=2158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yourlifeatlas.com\/pt\/wp-json\/wp\/v2\/tags?post=2158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}